{"id":22155,"date":"2025-01-01T17:01:41","date_gmt":"2025-01-01T16:01:41","guid":{"rendered":"http:\/\/housesaleitaly.com\/?post_type=property&#038;p=22155"},"modified":"2026-02-18T12:28:37","modified_gmt":"2026-02-18T11:28:37","slug":"apartamento-de-tres-habitaciones-en-edificio-renovado","status":"publish","type":"property","link":"https:\/\/housesaleitaly.com\/es\/property\/apartamento-de-tres-habitaciones-en-edificio-renovado\/","title":{"rendered":"Apartamento de tres habitaciones en edificio renovado"},"content":{"rendered":"\n<p>Presentamos un interesante piso de tres habitaciones con plaza de aparcamiento privada y s\u00f3tano situado en la muy c\u00e9ntrica via Regina Margherita, con acceso tambi\u00e9n desde via Leopoldo Jung, en un edificio recientemente renovado. El piso se encuentra en la tercera planta con ascensor. Desde la c\u00f3moda entrada se accede a la cocina-comedor abierta por dos lados y separada del sal\u00f3n desde el que se sale a un primer balc\u00f3n, \u00fatil para desayunar al aire libre. Desde el sal\u00f3n contiguo se accede a un balc\u00f3n m\u00e1s grande, perfecto para comer y relajarse al sol y tambi\u00e9n a la zona de noche a trav\u00e9s de un pasillo con amplio espacio para armarios y una zona de lavander\u00eda con conexiones para lavadora y espacio para secadora. La zona de noche consta de un dormitorio doble en esquina con dos ventanas y dos balcones redondeados, un dormitorio peque\u00f1o con vestidor y, por \u00faltimo, el cuarto de ba\u00f1o con ventana.<br>El nivel de los acabados es alto y moderno: ventanas de PVC con doble acristalamiento, puerta blindada, aire acondicionado fr\u00edo\/calor, caldera de calefacci\u00f3n aut\u00f3noma, sin barreras arquitect\u00f3nicas.<br>La vista desde el piso es muy relajante y la orientaci\u00f3n sur\/este garantiza muchas horas de sol y una gran luminosidad.<br>La propiedad incluye un s\u00f3tano y existe la posibilidad de adquirir una plaza de aparcamiento privada en la planta baja del edificio o en el s\u00f3tano por 30.000 euros o un garaje. Si est\u00e1s interesado en un piso de vacaciones, con habitaci\u00f3n para invitados o litera, como nuevo en cuanto a prestaciones y acabados, tranquilo y en la ubicaci\u00f3n m\u00e1s c\u00e9ntrica, y no quieres esperar los tiempos e inc\u00f3gnitas de la obra nueva, no dejes pasar esta oportunidad. \u00a1Ll\u00e1manos ahora para una visita!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentamos un interesante piso de tres habitaciones con plaza de aparcamiento privada y s\u00f3tano situado en la muy c\u00e9ntrica via Regina Margherita, con acceso tambi\u00e9n desde via Leopoldo Jung, en un edificio recientemente renovado. El piso se encuentra en la tercera planta con ascensor. Desde la c\u00f3moda entrada se accede a la cocina-comedor abierta por dos lados y separada del sal\u00f3n desde el que se sale a un primer balc\u00f3n, \u00fatil para desayunar al aire libre. Desde el sal\u00f3n contiguo se accede a un balc\u00f3n m\u00e1s grande, perfecto para comer y relajarse al sol y tambi\u00e9n a la zona de noche a trav\u00e9s de un pasillo con amplio espacio para armarios y una zona de lavander\u00eda con conexiones para lavadora y espacio para secadora. La zona de noche consta de un dormitorio doble en esquina con dos ventanas y dos balcones redondeados, un dormitorio peque\u00f1o con vestidor y, por \u00faltimo, el cuarto de ba\u00f1o con ventana.El nivel de los acabados es alto y moderno: ventanas de PVC con doble acristalamiento, puerta blindada, aire acondicionado fr\u00edo\/calor, caldera de calefacci\u00f3n aut\u00f3noma, sin barreras arquitect\u00f3nicas.La vista desde el piso es muy relajante y la orientaci\u00f3n sur\/este garantiza muchas horas de sol y una gran luminosidad.La propiedad incluye un s\u00f3tano y existe la posibilidad de adquirir una plaza de aparcamiento privada en la planta baja del edificio o en el s\u00f3tano por 30.000 euros o un garaje. Si est\u00e1s interesado en un piso de vacaciones, con habitaci\u00f3n para invitados o litera, como nuevo en cuanto a prestaciones y acabados, tranquilo y en la ubicaci\u00f3n m\u00e1s c\u00e9ntrica, y no quieres esperar los tiempos e inc\u00f3gnitas de la obra nueva, no dejes pasar esta oportunidad. \u00a1Ll\u00e1manos ahora para una visita!<\/p>\n","protected":false},"author":1,"featured_media":26933,"parent":0,"menu_order":0,"template":"","property_type":[182],"property_status":[238],"property_feature":[223,302,303,327,335],"property_label":[],"property_country":[189],"property_state":[188],"property_city":[193],"property_area":[],"class_list":["post-22155","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-apartamento-de-dos-dormitorios","property_status-en-venta","property_feature-aire-acondicionado","property_feature-ascensor","property_feature-balcon-es","property_feature-calefaccion-independiente","property_feature-sotano","property_country-italia-es","property_state-liguria-es","property_city-bordighera-es"],"property_meta":{"_edit_lock":["1771414195:1"],"_wpml_word_count":["298"],"_alp_processed":["1771414118"],"_thumbnail_id":["26933"],"_edit_last":["1"],"fave_currency":["EUR"],"fave_currency_info":["a:8:{s:2:\"id\";s:1:\"1\";s:13:\"currency_name\";s:4:\"Euro\";s:13:\"currency_code\";s:3:\"EUR\";s:15:\"currency_symbol\";s:3:\"\u20ac\";s:17:\"currency_position\";s:5:\"after\";s:16:\"currency_decimal\";s:1:\"0\";s:26:\"currency_decimal_separator\";s:1:\",\";s:27:\"currency_thousand_separator\";s:1:\".\";}"],"fave_property_price":["460000"],"fave_show_price_placeholder":["0"],"fave_property_size":["76"],"fave_property_size_prefix":["m\u00b2"],"fave_property_bedrooms":["2"],"fave_property_rooms":["3"],"fave_property_bathrooms":["1"],"fave_property_id":["IM1929"],"fave_property_map":["1"],"fave_property_location":["43.779410340201,7.6670652157929,18"],"houzez_geolocation_lat":["43.779410340201"],"houzez_geolocation_long":["7.6670652157929"],"fave_property_map_street_view":["show"],"fave_property_address":["Via Regina Margherita"],"fave_property_zip":["18012"],"houzez_featured_listing_date":[""],"fave_loggedintoview":["0"],"fave_prop_homeslider":["no"],"fave_energy_class":["B"],"fave_single_content_area":["simple"],"additional_features":["a:2:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:6:\"Planta\";s:29:\"fave_additional_feature_value\";s:7:\"tercera\";}i:1;a:2:{s:29:\"fave_additional_feature_title\";s:20:\"Tipo de calefacci\u00f3n\";s:29:\"fave_additional_feature_value\";s:3:\"gas\";}}"],"_genesis_title":["Apartamento en edificio renovado"],"_genesis_description":["Presentamos un interesante apartamento con plaza de aparcamiento privada y s\u00f3tano situado en la muy c\u00e9ntrica via Regina Margherita en Bordighera"],"_primary_term_property_feature":["302"],"_wpml_media_has_media":["1"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_wpml_location_migration_done":["1"],"_last_translation_edit_mode":["native-editor"],"houzez_total_property_views":["129"],"houzez_views_by_date":["a:61:{s:10:\"10-08-2025\";i:1;s:10:\"10-11-2025\";i:1;s:10:\"10-14-2025\";i:1;s:10:\"10-17-2025\";i:1;s:10:\"10-21-2025\";i:1;s:10:\"10-23-2025\";i:2;s:10:\"11-03-2025\";i:1;s:10:\"11-07-2025\";i:1;s:10:\"11-15-2025\";i:1;s:10:\"11-30-2025\";i:1;s:10:\"12-03-2025\";i:1;s:10:\"12-06-2025\";i:1;s:10:\"12-10-2025\";i:1;s:10:\"12-18-2025\";i:1;s:10:\"12-22-2025\";i:1;s:10:\"12-27-2025\";i:1;s:10:\"01-03-2026\";i:1;s:10:\"01-05-2026\";i:1;s:10:\"01-09-2026\";i:1;s:10:\"01-14-2026\";i:2;s:10:\"01-23-2026\";i:1;s:10:\"01-24-2026\";i:2;s:10:\"01-25-2026\";i:1;s:10:\"01-26-2026\";i:1;s:10:\"01-27-2026\";i:1;s:10:\"01-29-2026\";i:1;s:10:\"02-01-2026\";i:1;s:10:\"02-07-2026\";i:2;s:10:\"02-18-2026\";i:1;s:10:\"02-20-2026\";i:1;s:10:\"02-21-2026\";i:2;s:10:\"02-22-2026\";i:1;s:10:\"02-25-2026\";i:1;s:10:\"02-28-2026\";i:1;s:10:\"03-03-2026\";i:3;s:10:\"03-06-2026\";i:3;s:10:\"03-07-2026\";i:1;s:10:\"03-08-2026\";i:1;s:10:\"03-09-2026\";i:1;s:10:\"03-12-2026\";i:2;s:10:\"03-16-2026\";i:1;s:10:\"03-17-2026\";i:1;s:10:\"03-21-2026\";i:2;s:10:\"03-24-2026\";i:2;s:10:\"03-25-2026\";i:2;s:10:\"03-28-2026\";i:1;s:10:\"03-30-2026\";i:1;s:10:\"03-31-2026\";i:1;s:10:\"04-03-2026\";i:1;s:10:\"04-06-2026\";i:1;s:10:\"04-08-2026\";i:2;s:10:\"04-12-2026\";i:2;s:10:\"04-14-2026\";i:1;s:10:\"04-17-2026\";i:1;s:10:\"04-25-2026\";i:2;s:10:\"04-29-2026\";i:1;s:10:\"05-05-2026\";i:2;s:10:\"05-08-2026\";i:2;s:10:\"05-09-2026\";i:1;s:10:\"05-10-2026\";i:2;s:10:\"05-13-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-13 17:23:52"],"floor_plans":["a:2:{i:0;a:4:{s:15:\"fave_plan_title\";s:11:\"Apartamento\";s:15:\"fave_plan_rooms\";s:1:\"2\";s:19:\"fave_plan_bathrooms\";s:1:\"1\";s:15:\"fave_plan_image\";s:83:\"http:\/\/housesaleitaly.com\/wp-content\/uploads\/2025\/01\/planimetria-appartamento-1.jpg\";}i:1;a:2:{s:15:\"fave_plan_title\";s:21:\"Plaza de aparcamiento\";s:15:\"fave_plan_image\";s:79:\"http:\/\/housesaleitaly.com\/wp-content\/uploads\/2025\/01\/planimetria-posto-auto.jpg\";}}"],"wpr_secondary_image_id":["0"],"fave_featured":["0"],"fave_property_images":["26909","26914","26919","26924","26929"],"fave_agent_display_option":["agency_info"],"fave_property_agency":["18711"],"fave_single_top_area":["v2"]},"_links":{"self":[{"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/properties\/22155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/properties\/22155\/revisions"}],"predecessor-version":[{"id":28110,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/properties\/22155\/revisions\/28110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/media\/26933"}],"wp:attachment":[{"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/media?parent=22155"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_type?post=22155"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_status?post=22155"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_feature?post=22155"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_label?post=22155"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_country?post=22155"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_state?post=22155"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_city?post=22155"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/housesaleitaly.com\/es\/wp-json\/wp\/v2\/property_area?post=22155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}