{"id":22585,"date":"2025-01-05T19:24:24","date_gmt":"2025-01-05T18:24:24","guid":{"rendered":"http:\/\/housesaleitaly.com\/?post_type=property&#038;p=22585"},"modified":"2026-02-18T12:19:06","modified_gmt":"2026-02-18T11:19:06","slug":"geraeumige-dachgeschosswohnung-mit-meerblick","status":"publish","type":"property","link":"https:\/\/housesaleitaly.com\/de\/property\/geraeumige-dachgeschosswohnung-mit-meerblick\/","title":{"rendered":"Ger\u00e4umige Dachgeschosswohnung mit Meerblick"},"content":{"rendered":"\n<p>In der Via Roma, im Bereich des Studienzentrums, bieten wir eine ger\u00e4umige Dachgeschosswohnung an, bestehend aus einem Eingang in den Wohnbereich, einer bewohnbaren K\u00fcche mit Terrasse, einem Doppelwohnzimmer mit Terrasse, einem Badezimmer, einer Diele mit Einbauschr\u00e4nken, drei Doppelschlafzimmern, eines davon mit Terrasse, einem weiteren Badezimmer sowie einer Verbindung zum unausgebauten Dachgeschoss, bestehend aus einem gro\u00dfen Zimmer und einem Badezimmer.<br>Das Dachgeschoss ist bereits als zivile Wohnung eingetragen, so dass es auch mit Dachterrassen zu einer eigenst\u00e4ndigen Wohneinheit ausgebaut werden kann.<br>Die gesamte Wohnung ist sehr sonnig und bietet einen wundersch\u00f6nen Blick auf das Meer im Osten und die C\u00f4te d&#8217;Azur im Westen.<br>Die Wohnung ist ideal f\u00fcr gro\u00dfe Familien und kann auch gekauft werden, um Wohn- und B\u00fcrofl\u00e4chen zu teilen oder zwei Einheiten zu schaffen.<br>Es besteht die M\u00f6glichkeit, die Immobilie durch den Kauf einer Garage von \u00fcber 40 m\u00b2 zu vervollst\u00e4ndigen, die sich im Erdgeschoss befindet und direkt mit der Wohnung verbunden ist.<br>Die Heizung ist zentralisiert mit W\u00e4rmez\u00e4hlern.<br>Wenn Sie eine gro\u00dfe Wohnung im obersten Stockwerk suchen, die nicht laut ist und sich in einer ausgezeichneten Lage mit offenem Meerblick befindet, sollten Sie sich diese Gelegenheit nicht entgehen lassen. Durch eine individuelle Gestaltung k\u00f6nnen Sie eine fantastische Wohnung schaffen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Via Roma, im Bereich des Studienzentrums, bieten wir eine ger\u00e4umige Dachgeschosswohnung an, bestehend aus einem Eingang in den Wohnbereich, einer bewohnbaren K\u00fcche mit Terrasse, einem Doppelwohnzimmer mit Terrasse, einem Badezimmer, einer Diele mit Einbauschr\u00e4nken, drei Doppelschlafzimmern, eines davon mit Terrasse, einem weiteren Badezimmer sowie einer Verbindung zum unausgebauten Dachgeschoss, bestehend aus einem gro\u00dfen Zimmer und einem Badezimmer.Das Dachgeschoss ist bereits als zivile Wohnung eingetragen, so dass es auch mit Dachterrassen zu einer eigenst\u00e4ndigen Wohneinheit ausgebaut werden kann.Die gesamte Wohnung ist sehr sonnig und bietet einen wundersch\u00f6nen Blick auf das Meer im Osten und die C\u00f4te d&#8217;Azur im Westen.Die Wohnung ist ideal f\u00fcr gro\u00dfe Familien und kann auch gekauft werden, um Wohn- und B\u00fcrofl\u00e4chen zu teilen oder zwei Einheiten zu schaffen.Es besteht die M\u00f6glichkeit, die Immobilie durch den Kauf einer Garage von \u00fcber 40 m\u00b2 zu vervollst\u00e4ndigen, die sich im Erdgeschoss befindet und direkt mit der Wohnung verbunden ist.Die Heizung ist zentralisiert mit W\u00e4rmez\u00e4hlern.Wenn Sie eine gro\u00dfe Wohnung im obersten Stockwerk suchen, die nicht laut ist und sich in einer ausgezeichneten Lage mit offenem Meerblick befindet, sollten Sie sich diese Gelegenheit nicht entgehen lassen. Durch eine individuelle Gestaltung k\u00f6nnen Sie eine fantastische Wohnung schaffen!<\/p>\n","protected":false},"author":1,"featured_media":26859,"parent":0,"menu_order":0,"template":"","property_type":[179],"property_status":[222],"property_feature":[289,287],"property_label":[],"property_country":[190],"property_state":[187],"property_city":[205],"property_area":[],"class_list":["post-22585","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-drei-zimmer-wohnung","property_status-zu-verkaufen","property_feature-aufzug","property_feature-balkon","property_country-italien","property_state-ligurien","property_city-ventimiglia-de"],"property_meta":{"_edit_lock":["1771413653:1"],"_wpml_word_count":["251"],"_alp_processed":["1771413546"],"_thumbnail_id":["26859"],"_edit_last":["1"],"fave_currency":["EUR"],"fave_currency_info":["a:8:{s:2:\"id\";s:1:\"1\";s:13:\"currency_name\";s:4:\"Euro\";s:13:\"currency_code\";s:3:\"EUR\";s:15:\"currency_symbol\";s:3:\"\u20ac\";s:17:\"currency_position\";s:5:\"after\";s:16:\"currency_decimal\";s:1:\"0\";s:26:\"currency_decimal_separator\";s:1:\",\";s:27:\"currency_thousand_separator\";s:1:\".\";}"],"fave_property_price":["480000"],"fave_show_price_placeholder":["0"],"fave_property_size":["203"],"fave_property_size_prefix":["m\u00b2"],"fave_property_bedrooms":["3"],"fave_property_rooms":["6"],"fave_property_bathrooms":["3"],"fave_property_id":["IM1880"],"fave_property_map":["1"],"fave_property_location":["43.788205978274,7.6159463218998,18"],"houzez_geolocation_lat":["43.788205978274"],"houzez_geolocation_long":["7.6159463218998"],"fave_property_map_street_view":["show"],"fave_property_address":["Via Roma"],"fave_property_zip":["18039"],"houzez_featured_listing_date":[""],"fave_loggedintoview":["0"],"fave_prop_homeslider":["no"],"floor_plans":["a:2:{i:0;a:4:{s:15:\"fave_plan_title\";s:7:\"Wohnung\";s:15:\"fave_plan_rooms\";s:1:\"3\";s:19:\"fave_plan_bathrooms\";s:1:\"2\";s:15:\"fave_plan_image\";s:81:\"http:\/\/housesaleitaly.com\/wp-content\/uploads\/2025\/01\/Planimetria-appartamento.jpg\";}i:1;a:3:{s:15:\"fave_plan_title\";s:12:\"Dachgeschoss\";s:19:\"fave_plan_bathrooms\";s:1:\"1\";s:15:\"fave_plan_image\";s:77:\"http:\/\/housesaleitaly.com\/wp-content\/uploads\/2025\/01\/Planimetria-mansarda.jpg\";}}"],"fave_energy_class":["G"],"fave_energy_global_index":["175 kwh\/m\u00b2"],"fave_single_content_area":["simple"],"additional_features":["a:4:{i:0;a:2:{s:29:\"fave_additional_feature_title\";s:5:\"Etage\";s:29:\"fave_additional_feature_value\";s:7:\"sechste\";}i:1;a:2:{s:29:\"fave_additional_feature_title\";s:17:\"Anzahl der Etagen\";s:29:\"fave_additional_feature_value\";s:1:\"2\";}i:2;a:2:{s:29:\"fave_additional_feature_title\";s:11:\"Heizungsart\";s:29:\"fave_additional_feature_value\";s:19:\" Gas-Zentralheizung\";}i:3;a:2:{s:29:\"fave_additional_feature_title\";s:13:\"Balkonfl\u00e4che\";s:29:\"fave_additional_feature_value\";s:6:\"24 m\u00b2\";}}"],"_genesis_title":["Dachgeschosswohnung mit Meerblick"],"_genesis_description":["Wir bieten eine ger\u00e4umige Dachgeschosswohnung in der Via Roma, in der N\u00e4he des Studienzentrums von Ventimiglia"],"_primary_term_property_feature":["289"],"_wpml_media_has_media":["1"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_wpml_location_migration_done":["1"],"_last_translation_edit_mode":["native-editor"],"houzez_total_property_views":["168"],"houzez_views_by_date":["a:61:{s:10:\"12-25-2025\";i:1;s:10:\"12-27-2025\";i:1;s:10:\"12-30-2025\";i:1;s:10:\"01-05-2026\";i:2;s:10:\"01-06-2026\";i:1;s:10:\"01-07-2026\";i:1;s:10:\"01-14-2026\";i:1;s:10:\"01-22-2026\";i:1;s:10:\"01-24-2026\";i:1;s:10:\"01-25-2026\";i:1;s:10:\"01-26-2026\";i:1;s:10:\"01-29-2026\";i:1;s:10:\"02-01-2026\";i:1;s:10:\"02-02-2026\";i:2;s:10:\"02-07-2026\";i:1;s:10:\"02-14-2026\";i:1;s:10:\"02-15-2026\";i:1;s:10:\"02-18-2026\";i:3;s:10:\"02-19-2026\";i:1;s:10:\"02-20-2026\";i:1;s:10:\"02-22-2026\";i:1;s:10:\"02-23-2026\";i:1;s:10:\"02-26-2026\";i:5;s:10:\"02-28-2026\";i:1;s:10:\"03-01-2026\";i:1;s:10:\"03-02-2026\";i:5;s:10:\"03-04-2026\";i:1;s:10:\"03-06-2026\";i:2;s:10:\"03-12-2026\";i:2;s:10:\"03-16-2026\";i:2;s:10:\"03-17-2026\";i:1;s:10:\"03-18-2026\";i:1;s:10:\"03-19-2026\";i:1;s:10:\"03-21-2026\";i:2;s:10:\"03-24-2026\";i:3;s:10:\"03-25-2026\";i:1;s:10:\"03-26-2026\";i:1;s:10:\"03-28-2026\";i:1;s:10:\"03-30-2026\";i:1;s:10:\"03-31-2026\";i:1;s:10:\"04-04-2026\";i:1;s:10:\"04-06-2026\";i:1;s:10:\"04-07-2026\";i:1;s:10:\"04-08-2026\";i:2;s:10:\"04-09-2026\";i:1;s:10:\"04-10-2026\";i:1;s:10:\"04-12-2026\";i:1;s:10:\"04-13-2026\";i:2;s:10:\"04-17-2026\";i:1;s:10:\"04-19-2026\";i:1;s:10:\"04-25-2026\";i:1;s:10:\"04-26-2026\";i:1;s:10:\"04-28-2026\";i:1;s:10:\"05-01-2026\";i:1;s:10:\"05-02-2026\";i:1;s:10:\"05-03-2026\";i:1;s:10:\"05-05-2026\";i:1;s:10:\"05-07-2026\";i:1;s:10:\"05-08-2026\";i:2;s:10:\"05-09-2026\";i:2;s:10:\"05-10-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-10 22:04:59"],"wpr_secondary_image_id":["0"],"fave_featured":["0"],"fave_property_images":["26862","26867","26872","26877","26857"],"fave_agent_display_option":["agency_info"],"fave_property_agency":["18711"],"fave_single_top_area":["v2"]},"_links":{"self":[{"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/properties\/22585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/properties\/22585\/revisions"}],"predecessor-version":[{"id":28082,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/properties\/22585\/revisions\/28082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/media\/26859"}],"wp:attachment":[{"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/media?parent=22585"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_type?post=22585"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_status?post=22585"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_feature?post=22585"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_label?post=22585"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_country?post=22585"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_state?post=22585"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_city?post=22585"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/housesaleitaly.com\/de\/wp-json\/wp\/v2\/property_area?post=22585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}